{"id":439,"date":"2016-06-30T19:19:43","date_gmt":"2016-06-30T19:19:43","guid":{"rendered":"http:\/\/www.mindsas.com\/alvaralice-wp\/?page_id=439"},"modified":"2016-07-13T19:40:04","modified_gmt":"2016-07-13T19:40:04","slug":"publications","status":"publish","type":"page","link":"https:\/\/alvaralice.org\/en\/publications\/","title":{"rendered":"Publications"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-439","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v20.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Publications - Foundation Alvaralice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alvaralice.org\/en\/publications\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publications\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alvaralice.org\/en\/publications\/\" \/>\n<meta property=\"og:site_name\" content=\"Foundation Alvaralice\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-13T19:40:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/alvaralice.org\/en\/publications\/\",\"url\":\"https:\/\/alvaralice.org\/en\/publications\/\",\"name\":\"Publications - Foundation Alvaralice\",\"isPartOf\":{\"@id\":\"https:\/\/alvaralice.org\/en\/#website\"},\"datePublished\":\"2016-06-30T19:19:43+00:00\",\"dateModified\":\"2016-07-13T19:40:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/alvaralice.org\/en\/publications\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/alvaralice.org\/en\/publications\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/alvaralice.org\/en\/publications\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/alvaralice.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/alvaralice.org\/en\/#website\",\"url\":\"https:\/\/alvaralice.org\/en\/\",\"name\":\"Foundation Alvaralice\",\"description\":\"La Fundaci\u00f3n Alvaralice es una entidad de car\u00e1cter privado, sin \u00e1nimo de lucro, creada en el 2003 en Cali\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/alvaralice.org\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Publications - Foundation Alvaralice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alvaralice.org\/en\/publications\/","og_locale":"en_US","og_type":"article","og_title":"Publications","og_url":"https:\/\/alvaralice.org\/en\/publications\/","og_site_name":"Foundation Alvaralice","article_modified_time":"2016-07-13T19:40:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alvaralice.org\/en\/publications\/","url":"https:\/\/alvaralice.org\/en\/publications\/","name":"Publications - Foundation Alvaralice","isPartOf":{"@id":"https:\/\/alvaralice.org\/en\/#website"},"datePublished":"2016-06-30T19:19:43+00:00","dateModified":"2016-07-13T19:40:04+00:00","breadcrumb":{"@id":"https:\/\/alvaralice.org\/en\/publications\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alvaralice.org\/en\/publications\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alvaralice.org\/en\/publications\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alvaralice.org\/en\/"},{"@type":"ListItem","position":2,"name":"Publications"}]},{"@type":"WebSite","@id":"https:\/\/alvaralice.org\/en\/#website","url":"https:\/\/alvaralice.org\/en\/","name":"Foundation Alvaralice","description":"La Fundaci\u00f3n Alvaralice es una entidad de car\u00e1cter privado, sin \u00e1nimo de lucro, creada en el 2003 en Cali","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alvaralice.org\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/pages\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":5,"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/pages\/439\/revisions"}],"predecessor-version":[{"id":1368,"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/pages\/439\/revisions\/1368"}],"wp:attachment":[{"href":"https:\/\/alvaralice.org\/en\/wp-json\/wp\/v2\/media?parent=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}